{"id":6270,"date":"2019-05-10T08:00:41","date_gmt":"2019-05-10T06:00:41","guid":{"rendered":"https:\/\/www.vsxdesign.com\/blog\/?p=6270"},"modified":"2019-05-09T19:11:58","modified_gmt":"2019-05-09T17:11:58","slug":"facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo","status":"publish","type":"post","link":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/","title":{"rendered":"Facebook sta esagerando nel censurare l&#8217;estremismo e il nazionalismo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Facebook \u00e8 stato messo sotto pressione dall&#8217;opinione pubblica per rimuovere contenuti estremisti, disinformazione e abuso dalle sue piattaforme per diversi anni. Ha affermato di aver compiuto importanti passi avanti, impiegando migliaia di moderatori per rivedere i contenuti segnalati e implementare algoritmi per <a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-rende-piu-difficile-pubblicare-annunci-discriminatori\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"rilevare e rimuovere contenuti inappropriati (opens in a new tab)\">rilevare e rimuovere contenuti inappropriati<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo gli <a rel=\"noreferrer noopener\" aria-label=\"attacchi terroristici di Christchurch (opens in a new tab)\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-ha-rimosso-oltre-1-5-milioni-di-video-delle-riprese-in-nuova-zelanda\/\" target=\"_blank\">attacchi terroristici di Christchurch<\/a> a marzo, in cui un presunto suprematista bianco australiano ha ucciso dozzine di persone in due moschee e trasmesso in diretta su Facebook, una nuova <strong>ondata di condanne<\/strong> ha colpito Facebook e altre piattaforme online, accusate di agevolare la propaganda terroristica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prossima settimana, si prevede che i leader mondiali e gli amministratori delegati delle pi\u00f9 grandi piattaforme online del mondo si incontreranno a Parigi. Si tratta di una riunione co-ospitata dal primo ministro della Nuova Zelanda, Jacinda Ardern e dal presidente francese, Emmanuel Macron, per <a rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\" href=\"https:\/\/eandt.theiet.org\/content\/articles\/2019\/04\/world-leaders-and-tech-executives-to-pledge-to-fight-terrorism-online\/\" target=\"_blank\">impegnarsi a eliminare i contenuti terroristici online<\/a>\u00a0. <\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#LAssociated_Press_AP_ha_presentato_una_denuncia_dicendo_che_Facebook_ha_esagerato_nellindividuare_e_rimuovere_contenuti_estremisti\" >L&#8217;Associated Press (AP) ha presentato una denuncia dicendo che Facebook ha esagerato nell&#8217;individuare e rimuovere contenuti estremisti.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#contenuti_sanguinosi_ed_estremisti_come_video_di_esecuzioni_fotografie_di_teste_mozzate_e_propaganda_islamista_sono_rimasti_facili_da_trovare\" >contenuti sanguinosi ed estremisti, come video di esecuzioni, fotografie di teste mozzate e propaganda islamista, sono rimasti facili da trovare<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#Altre_pagine_che_sono_rimaste_individuabili_includono_%E2%80%9CThe_American_Nazi_Party%E2%80%9D_%E2%80%9CNew_Aryan_Empire%E2%80%9D_e_%E2%80%9CAryan_Brotherhood_Headquarters%E2%80%9D\" >Altre pagine che sono rimaste individuabili includono &#8220;The American Nazi Party&#8221;, &#8220;New Aryan Empire&#8221; e &#8220;Aryan Brotherhood Headquarters&#8221;.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#In_risposta_allo_studio_Facebook_ha_affermato_che_i_suoi_meccanismi_non_sono_perfetti_ma_stanno_migliorando\" >In risposta allo studio, Facebook ha affermato che i suoi meccanismi non sono perfetti, ma stanno migliorando:<\/a><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"LAssociated_Press_AP_ha_presentato_una_denuncia_dicendo_che_Facebook_ha_esagerato_nellindividuare_e_rimuovere_contenuti_estremisti\"><\/span>L&#8217;Associated Press (AP) ha presentato una denuncia dicendo che <strong>Facebook ha esagerato nell&#8217;individuare e rimuovere contenuti estremisti.<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nel corso di cinque mesi l&#8217;anno scorso, dei ricercatori hanno monitorato pagine accessibili pubblicamente, controllate da utenti affiliati a gruppi terroristici. Durante questo periodo, <strong>solo il 38%<\/strong> dei post che presentavano simboli di gruppi estremisti furono rimossi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mentre lo studio ha dei limiti, in particolare perch\u00e9 le piattaforme dei <a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/intelligenza-artificiale-generativa\/\">social media<\/a> normalmente rifiutano di condividere i dati anonimi con i ricercatori, questi ultimi hanno affermato che, le dichiarazioni di Facebook, secondo cui i suoi sistemi rimuovono la maggior parte dei contenuti estremisti, sono quasi certamente imprecise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;AP ha rivisto in modo indipendente i contenuti di estremisti su Facebook, scoprendo che :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"contenuti_sanguinosi_ed_estremisti_come_video_di_esecuzioni_fotografie_di_teste_mozzate_e_propaganda_islamista_sono_rimasti_facili_da_trovare\"><\/span>contenuti sanguinosi ed estremisti, come video di esecuzioni, fotografie di teste mozzate e propaganda islamista, sono rimasti facili da trovare<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">a causa della loro presenza nei risultati di ricerca. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una pagina che non \u00e8 stata rilevata da Facebook includeva l&#8217;intestazione &#8220;Lo stato islamico&#8221; in inglese, sopra una fotografia di una nube di funghi; questa pagina molto probabilmente \u00e8 sfuggita ai sistemi di Facebook a causa del fatto che il testo \u00e8 stato inserito nella foto. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Altre_pagine_che_sono_rimaste_individuabili_includono_%E2%80%9CThe_American_Nazi_Party%E2%80%9D_%E2%80%9CNew_Aryan_Empire%E2%80%9D_e_%E2%80%9CAryan_Brotherhood_Headquarters%E2%80%9D\"><\/span>Altre pagine che sono rimaste individuabili includono &#8220;The American Nazi Party&#8221;, &#8220;New Aryan Empire&#8221; e &#8220;Aryan Brotherhood Headquarters&#8221;. <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;AP ha anche scoperto che <strong>Facebook generava automaticamente video usando materiale estremista<\/strong>, come video animati contenenti messaggi antisemiti che affermavano: &#8220;Grazie per essere qui, da Facebook&#8221; e il simbolo &#8220;Mi piace&#8221; istantaneamente riconoscibile di Facebook. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hany Farid, un esperto di informatica forense all&#8217;Universit\u00e0 della California-Berkeley e consulente del Counter-Extremism Project, ha dichiarato all&#8217;AP che <a href=\"https:\/\/www.vsxdesign.com\/blog\/tecnologia\/informatica\/lintelligenza-artificiale-di-facebook-e-stupida\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"i sistemi di apprendimento automatico di Facebook (opens in a new tab)\">i sistemi di apprendimento automatico di Facebook<\/a> per la rilevazione dell&#8217;estremismo stavano fallendo e che la societ\u00e0 non era disposta ad accettare le spese per affrontare il problema .<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"In_risposta_allo_studio_Facebook_ha_affermato_che_i_suoi_meccanismi_non_sono_perfetti_ma_stanno_migliorando\"><\/span>In risposta allo studio, Facebook ha affermato che i suoi meccanismi non sono perfetti, ma stanno migliorando: <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Dopo aver effettuato ingenti investimenti, stiamo rilevando e rimuovendo i contenuti a sfondo terroristico ad un tasso di successo molto pi\u00f9 alto rispetto a due anni fa. Non rivendichiamo di trovare tutto e rimaniamo vigili nei nostri sforzi contro i gruppi terroristici di tutto il mondo.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">ha detto un portavoce. in una dichiarazione.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente, <a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-bandisce-nazionalisti-e-separatisti-bianchi-dalla-sua-piattaforma\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Facebook ha messo al bando una manciata di provocatori di estrema destra (opens in a new tab)\">Facebook ha messo al bando una manciata di provocatori di estrema destra<\/a> di alto profilo, tra cui Milo Yiannopoulos, Paul Nehlen e Laura Loomer: una mossa che ha attirato le critiche del presidente degli Stati Uniti Donald Trump.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo ha fatto seguito all&#8217;annuncio che il\u00a0<a href=\"https:\/\/eandt.theiet.org\/content\/articles\/2019\/03\/facebook-boots-out-white-nationalism-in-wake-of-christchurch-massacre\/\">materiale<\/a> che promuove il nazionalismo bianco e il separatismo bianco &#8211; i movimenti estremisti a cui sarebbe stato affiliato lo sparatutto di Christchurch &#8211; sarebbe stato bandito dalla piattaforma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facebook \u00e8 stato messo sotto pressione dall&#8217;opinione pubblica per rimuovere contenuti estremisti, disinformazione e abuso dalle sue piattaforme per diversi anni. Ha affermato di aver compiuto importanti passi avanti, impiegando migliaia di moderatori per rivedere i contenuti segnalati e implementare algoritmi per rilevare e rimuovere contenuti inappropriati. Dopo gli attacchi terroristici di Christchurch a marzo,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Facebook sta esagerando nel censurare l'estremismo e il nazionalismo #censurafacebook #facebookcontrogliestremisti #noagliestremisti","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10],"tags":[82],"class_list":["post-6270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social","tag-facebook"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facebook sta esagerando nel censurare l&#039;estremismo e il nazionalismo<\/title>\n<meta name=\"description\" content=\"Facebook \u00e8 stato messo sotto pressione dall&#039;opinione pubblica per rimuovere contenuti estremisti dalle sue piattaforme ma ora forse esagera con la censura\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook sta esagerando nel censurare l&#039;estremismo e il nazionalismo\" \/>\n<meta property=\"og:description\" content=\"Facebook \u00e8 stato messo sotto pressione dall&#039;opinione pubblica per rimuovere contenuti estremisti dalle sue piattaforme ma ora forse esagera con la censura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/\" \/>\n<meta property=\"og:site_name\" content=\"vsx blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vsxdesign\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-10T06:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valerio sanna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vsxdesign\" \/>\n<meta name=\"twitter:site\" content=\"@vsxdesign\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"valerio sanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/\"},\"author\":{\"name\":\"valerio sanna\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/person\\\/09283cb51d9fb4611174ef2ae909f14d\"},\"headline\":\"Facebook sta esagerando nel censurare l&#8217;estremismo e il nazionalismo\",\"datePublished\":\"2019-05-10T06:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/\"},\"wordCount\":587,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1\",\"keywords\":[\"facebook\"],\"articleSection\":[\"Social\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/\",\"name\":\"Facebook sta esagerando nel censurare l'estremismo e il nazionalismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1\",\"datePublished\":\"2019-05-10T06:00:41+00:00\",\"description\":\"Facebook \u00e8 stato messo sotto pressione dall'opinione pubblica per rimuovere contenuti estremisti dalle sue piattaforme ma ora forse esagera con la censura\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1\",\"width\":1024,\"height\":683,\"caption\":\"facebook censura troppo gli estremisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/social\\\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facebook sta esagerando nel censurare l&#8217;estremismo e il nazionalismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\",\"name\":\"vsx blog\",\"description\":\"il mio punto di vista sul web, la tecnologia e l&#039;innovazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\",\"name\":\"VSX design\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/VSX_logo_2017-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/VSX_logo_2017-1.png\",\"width\":346,\"height\":133,\"caption\":\"VSX design\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vsxdesign\\\/\",\"https:\\\/\\\/x.com\\\/vsxdesign\",\"https:\\\/\\\/www.instagram.com\\\/buonumorismo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/valerio-sanna\",\"https:\\\/\\\/www.pinterest.it\\\/vsxblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/person\\\/09283cb51d9fb4611174ef2ae909f14d\",\"name\":\"valerio sanna\",\"description\":\"Vsx Blog : il mio punto di vista sul mondo del web, dell'innovazione e della scienza.\",\"sameAs\":[\"http:\\\/\\\/www.vsxdesign.com\\\/blog\",\"https:\\\/\\\/x.com\\\/vsxdesign\"],\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/author\\\/valerio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook sta esagerando nel censurare l'estremismo e il nazionalismo","description":"Facebook \u00e8 stato messo sotto pressione dall'opinione pubblica per rimuovere contenuti estremisti dalle sue piattaforme ma ora forse esagera con la censura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/","og_locale":"it_IT","og_type":"article","og_title":"Facebook sta esagerando nel censurare l'estremismo e il nazionalismo","og_description":"Facebook \u00e8 stato messo sotto pressione dall'opinione pubblica per rimuovere contenuti estremisti dalle sue piattaforme ma ora forse esagera con la censura","og_url":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/","og_site_name":"vsx blog","article_publisher":"https:\/\/www.facebook.com\/vsxdesign\/","article_published_time":"2019-05-10T06:00:41+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg","type":"image\/jpeg"}],"author":"valerio sanna","twitter_card":"summary_large_image","twitter_creator":"@vsxdesign","twitter_site":"@vsxdesign","twitter_misc":{"Scritto da":"valerio sanna","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#article","isPartOf":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/"},"author":{"name":"valerio sanna","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/person\/09283cb51d9fb4611174ef2ae909f14d"},"headline":"Facebook sta esagerando nel censurare l&#8217;estremismo e il nazionalismo","datePublished":"2019-05-10T06:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/"},"wordCount":587,"commentCount":0,"publisher":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1","keywords":["facebook"],"articleSection":["Social"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/","url":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/","name":"Facebook sta esagerando nel censurare l'estremismo e il nazionalismo","isPartOf":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#primaryimage"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1","datePublished":"2019-05-10T06:00:41+00:00","description":"Facebook \u00e8 stato messo sotto pressione dall'opinione pubblica per rimuovere contenuti estremisti dalle sue piattaforme ma ora forse esagera con la censura","breadcrumb":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1","width":1024,"height":683,"caption":"facebook censura troppo gli estremisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/facebook-sta-esagerando-nel-censurare-lestremismo-e-il-nazionalismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vsxdesign.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Facebook sta esagerando nel censurare l&#8217;estremismo e il nazionalismo"}]},{"@type":"WebSite","@id":"https:\/\/www.vsxdesign.com\/blog\/#website","url":"https:\/\/www.vsxdesign.com\/blog\/","name":"vsx blog","description":"il mio punto di vista sul web, la tecnologia e l&#039;innovazione","publisher":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vsxdesign.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vsxdesign.com\/blog\/#organization","name":"VSX design","url":"https:\/\/www.vsxdesign.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/03\/VSX_logo_2017-1.png","contentUrl":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/03\/VSX_logo_2017-1.png","width":346,"height":133,"caption":"VSX design"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vsxdesign\/","https:\/\/x.com\/vsxdesign","https:\/\/www.instagram.com\/buonumorismo\/","https:\/\/www.linkedin.com\/in\/valerio-sanna","https:\/\/www.pinterest.it\/vsxblog"]},{"@type":"Person","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/person\/09283cb51d9fb4611174ef2ae909f14d","name":"valerio sanna","description":"Vsx Blog : il mio punto di vista sul mondo del web, dell'innovazione e della scienza.","sameAs":["http:\/\/www.vsxdesign.com\/blog","https:\/\/x.com\/vsxdesign"],"url":"https:\/\/www.vsxdesign.com\/blog\/author\/valerio\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/facebook-censura-troppo.jpg?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/6270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/comments?post=6270"}],"version-history":[{"count":0,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/6270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/media\/6273"}],"wp:attachment":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/media?parent=6270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/categories?post=6270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/tags?post=6270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}