{"id":15537,"date":"2025-08-07T10:33:15","date_gmt":"2025-08-07T08:33:15","guid":{"rendered":"https:\/\/www.vsxdesign.com\/blog\/?p=15537"},"modified":"2025-08-07T10:33:16","modified_gmt":"2025-08-07T08:33:16","slug":"battere-il-mercato-azionario","status":"publish","type":"post","link":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/","title":{"rendered":"Battere il mercato azionario \u00e8 possibile con i computer?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ci aspettiamo molto dall&#8217;intelligenza artificiale (<a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/i-contenuti-generati-dallia-spesso-falliscono\/\">IA<\/a>): <a aria-label=\"Spotify (opens in a new tab)\" rel=\"noreferrer noopener\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/commercio-e-ricchezza\/spotify-ha-raggiunto-i-100-milioni-di-abbonati-a-pagamento\/\" target=\"_blank\">Spotify<\/a> seleziona i brani per la tua playlist.\u00a0Il tuo telefono ha imparato a riconoscere il tuo viso, anche se sei spettinato.\u00a0E le auto a guida autonoma, ci viene promesso, sono dietro l&#8217;angolo. Ma ecco qualcosa che probabilmente non avremo mai: un computer per battere il mercato azionario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non \u00e8 per mancanza di interesse per la parte di Wall Street.&nbsp;Lo sforzo di modellare scientificamente i mercati, iniziato a met\u00e0 degli anni &#8217;80, ha assorbito i talenti di alcuni dei pi\u00f9 brillanti laureati in matematica e informatica.&nbsp;Una manciata di gestori segreti di hedge fund &#8211; tra cui&nbsp;Renaissance Technologies&nbsp;,&nbsp;PDT Partners&nbsp;e&nbsp;DE Shaw&nbsp;&#8211; hanno avuto ricavi straordinari.&nbsp;Ma molte delle principali operazioni di oggi, sono le stesse di decenni fa.&nbsp;E probabilmente non sei abbastanza ricco o connesso per investire in questo modo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per definizione, la maggior parte degli investitori non pu\u00f2 battere il mercato azionario e ogni computer che trova momentaneamente una formula vincente dovr\u00e0 presto affrontare altri che cercano di superarlo.\u00a0Ma si scopre che investire \u00e8 anche semplicemente pi\u00f9 difficile di, ad esempio, prevedere il tuo prossimo acquisto su <a href=\"https:\/\/www.vsxdesign.com\/blog\/tecnologia\/accessori\/amazon-sa-come-ti-senti\/\">Amazon<\/a>.\u00a0&#8220;\u00c8 uno dei problemi pi\u00f9 difficili nell&#8217;apprendimento automatico delle macchine&#8221;, afferma Ciamac Moallemi, professore alla Columbia Business School e preside alla\u00a0Bourbaki LLC\u00a0.\u00a0Qui ci sono solo alcuni dei problemi diabolici che gli ingegneri finanziari stanno cercando di risolvere:<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#I_dati_continuano_a_cambiare\" >I dati continuano a cambiare<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#Ce_piu_rumore_che_segnale\" >C&#8217;\u00e8 pi\u00f9 rumore che segnale<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#Migliorare_le_previsioni_anche_di_poco\" >Migliorare le previsioni, anche di poco<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#I_rumori_di_fondo_per_battere_il_mercato_azionario\" >I rumori di fondo per battere il mercato azionario<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-i-dati-continuano-a-cambiare\"><span class=\"ez-toc-section\" id=\"I_dati_continuano_a_cambiare\"><\/span>I dati continuano a cambiare<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un esempio di dati stazionari potrebbe essere la distanza tra l&#8217;occhio sinistro e il naso.&nbsp;A meno che tu non faccia un intervento di chirurgia plastica, \u00e8 una costante.&nbsp;Se una macchina viene alimentata con centinaia di foto, sar\u00e0 in grado di identificarti con un&#8217;elevata precisione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nei mercati finanziari, i dati possono cambiare drasticamente e in modi senza precedenti, ad esempio quando i tassi d&#8217;interesse sono diventati negativi in \u200b\u200bgran parte dell&#8217;Europa e del Giappone nel 2013. Altri cambiamenti possono essere pi\u00f9 banali. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-c-pi-rumore-che-segnale\"><span class=\"ez-toc-section\" id=\"Ce_piu_rumore_che_segnale\"><\/span>C&#8217;\u00e8 pi\u00f9 rumore che segnale<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gli stock si muovono continuamente e non sempre per una ragione visibile.\u00a0La maggior parte delle mosse di mercato sono ci\u00f2 che gli economisti chiamano <strong>noise trading.<\/strong>\u00a0Per tornare all&#8217;analogia del riconoscimento dell&#8217;immagine, immagina un computer che cerchi di identificare le persone nelle foto scattate al buio.\u00a0La maggior parte dei dati in queste immagini sono pixel neri che si confondono nel rumore di fondo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un segnale ovvio, ad esempio, per comprare azioni il primo giorno di ogni mese, non \u00e8 di grande utilit\u00e0.\u00a0Se questo ha funzionato in passato, probabilmente era solo un colpo di fortuna, e anche se non lo fosse, sar\u00e0 presto scoperto e scambiato da altri.\u00a0Cos\u00ec i ricercatori si sono concentrati su segnali molto deboli, quelli che potevano prevedere il prezzo futuro con <strong>solo il 51% di certezza<\/strong>.\u00a0&#8220;Stavamo cercando modelli che fossero appena ai margini del rilevamento&#8221;, afferma Whitney.\u00a0La maggior parte degli investitori non pu\u00f2 trarre vantaggio da tali modelli.\u00a0Per farli funzionare, i money manager devono combinare migliaia di scommesse e ingrandirle con la leva finanziaria &#8211; investendo con denaro preso in prestito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-migliorare-le-previsioni-anche-di-poco\"><span class=\"ez-toc-section\" id=\"Migliorare_le_previsioni_anche_di_poco\"><\/span>Migliorare le previsioni, anche di poco<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"h-la-previsione-pu-essere-migliorata-solo-di-poco-costringendo-i-trader-a-cercare-altri-vantaggi-nell-investire-un-problema-proficuo-da-risolvere-sono-i-costi-di-transazione\">La previsione pu\u00f2 essere migliorata solo di poco, costringendo i trader a cercare altri vantaggi.&nbsp;Nell&#8217;investire, un problema proficuo da risolvere sono i costi di transazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il costo evidente della transazione \u00e8 la commissione che il broker addebita.\u00a0Ma c&#8217;\u00e8 anche qualcosa chiamato <strong>slippage<\/strong>, che rappresenta il prezzo quotato &#8211; $ 135 per una quota di\u00a0IBM Corp.\u00a0, ad esempio &#8211; essendo relativo al numero di azioni che si desidera acquistare.\u00a0Potresti riuscire a comprare solo 100 azioni a $ 135;\u00a0acquistare 1.000 azioni richiederebbe un prezzo pi\u00f9 alto per attirare nuovi venditori.\u00a0Il costo medio potrebbe quindi essere $ 136.\u00a0L&#8217;unico modo per conoscere il vero prezzo, con lo slippage, \u00e8 di negoziare sul mercato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Senza la comprensione dei costi di transazione, un&#8217;azienda potrebbe scambiare solo 1.000 azioni, per non rischiare troppo slittamenti.\u00a0Una societ\u00e0 che sa, con una probabilit\u00e0 dell&#8217;80%, che si possono comprare 5.000 azioni senza spostare il mercato pu\u00f2 fare una scommessa pi\u00f9 grande.\u00a0Molti nel settore dicono che Renaissance ha la comprensione pi\u00f9 avanzata dei costi di transazione, e questo \u00e8 un segreto per il suo <strong>ineguagliabile track record<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per guadagnare ulteriormente, alcuni manager fanno<strong> trading ad alta frequenza<\/strong>, cos\u00ec possono agire da market maker, guadagnando denaro sia da acquirenti che da venditori.\u00a0Ma altrettanto importante \u00e8 la tempistica d&#8217;esecuzione di queste piattaforme.\u00a0Per battere il mercato azionario \u00e8 come se\u00a0<a aria-label=\"Warren Buffett (opens in a new tab)\" href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjU05ON1a7iAhUHyKQKHZ8DAAQQFjAAegQIARAB&amp;url=https%3A%2F%2Fit.wikipedia.org%2Fwiki%2FWarren_Buffett&amp;usg=AOvVaw1hjDZMd-B_jJaVQAAoG8cb\" target=\"_blank\" rel=\"noreferrer noopener\">Warren Buffett<\/a>\u00a0avesse i propri trader seduti sul pavimento della Borsa di New York piuttosto che usare una societ\u00e0 di intermediazione. Quei trader l\u00ec seduti potrebbero dirgli cose sull&#8217;umore della borsa che i mediatori non saprebbero mai.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-i-rumori-di-fondo-per-battere-il-mercato-azionario\"><span class=\"ez-toc-section\" id=\"I_rumori_di_fondo_per_battere_il_mercato_azionario\"><\/span>I rumori di fondo per battere il mercato azionario<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per quanto gli <a aria-label=\"hedge fund (opens in a new tab)\" href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=2&amp;cad=rja&amp;uact=8&amp;ved=2ahUKEwjOpJWc1a7iAhVyThUIHQuJC8kQFjABegQIABAB&amp;url=https%3A%2F%2Fit.wikipedia.org%2Fwiki%2FFondo_speculativo&amp;usg=AOvVaw3vui7gh8prOAY6d83_HFAu\" target=\"_blank\" rel=\"noreferrer noopener\">hedge fund<\/a> stiano usando i computer per battere il mercato azionario e il riconoscimento dei pattern, trovare nuovi segnali di mercato \u00e8 ancora uno sforzo umano.\u00a0I manager impiegano enormi staff, a volte centinaia di trader, e partecipano a conferenze per reclutare nuovi laureandi promettenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per costruire un sistema di investimento veramente autonomo, in cui il computer stia pensando a segnali e strategie da provare per battere il mercato azionario, i ricercatori probabilmente dovranno risolvere il problema della causalit\u00e0.\u00a0Ci\u00f2 significa non solo notare che, ad esempio, un aumento di un determinato stock \u00e8 spesso accompagnato da un aumento dei tassi di interesse, ma anche dalla possibilit\u00e0 di giungere ad un motivo.\u00a0Gli umani sono bravi in questo tipo di pensiero, ma l&#8217;<a aria-label=\"IA ha iniziato solo ora a fare progressi (opens in a new tab)\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/industria-e-innovazione\/deepmind-puo-prevedere-la-produzione-di-una-turbina-eolica\/\" target=\"_blank\" rel=\"noreferrer noopener\">IA ha iniziato solo ora a fare progressi<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un altro metodo, noto come <strong>deep learning<\/strong>, ha guidato i recenti progressi nell&#8217;IA, come il riconoscimento dell&#8217;immagine e la traduzione vocale. Questo sistema affronta il problema del rumore prevedendo non i prezzi delle azioni, ma i cambiamenti nei fondamentali aziendali, come i margini di profitto, che alla fine determinano i rendimenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La natura contraddittoria del commercio significa che la maggior parte degli sviluppi rimane avvolta nella segretezza.&nbsp;Ci\u00f2 rende gli scienziati di alta qualit\u00e0 difficili da reclutare.&nbsp;Gli scienziati amano pubblicare e collaborare.&nbsp;&#8220;Amiamo scoprire cose nuove sui mercati e avere una grande comunit\u00e0 di persone all&#8217;interno dell&#8217;azienda con cui siamo in grado di condividere risultati, ma sfortunatamente non possiamo comunicarli a nessuno&#8221;, afferma Pete Muller, fondatore di PDT Partners LLC , un pioniere nel settore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;utilizzo di computer per battere il mercato azionario \u00e8 una sfida davvero difficile, ma non penso sia impossibile. Sicuramente \u00e8 una ricerca affascinante e, vista l&#8217;attrazione della razza umana per il denaro, durer\u00e0 ancora per molto tempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci aspettiamo molto dall&#8217;intelligenza artificiale (IA): Spotify seleziona i brani per la tua playlist.\u00a0Il tuo telefono ha imparato a riconoscere il tuo viso, anche se sei spettinato.\u00a0E le auto a guida autonoma, ci viene promesso, sono dietro l&#8217;angolo. Ma ecco qualcosa che probabilmente non avremo mai: un computer per battere il mercato azionario. Non \u00e8&#8230;<\/p>\n","protected":false},"author":1,"featured_media":6457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[93],"tags":[],"class_list":["post-15537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investimenti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Battere il mercato azionario \u00e8 possibile con i computer? - vsx blog<\/title>\n<meta name=\"description\" content=\"Ci aspettiamo molto dall&#039;intelligenza artificiale ma ecco qualcosa che forse non avremo mai: un computer per battere il mercato azionario\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Battere il mercato azionario \u00e8 possibile con i computer? - vsx blog\" \/>\n<meta property=\"og:description\" content=\"Ci aspettiamo molto dall&#039;intelligenza artificiale ma ecco qualcosa che forse non avremo mai: un computer per battere il mercato azionario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/\" \/>\n<meta property=\"og:site_name\" content=\"vsx blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vsxdesign\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-07T08:33:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T08:33:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valerio sanna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vsxdesign\" \/>\n<meta name=\"twitter:site\" content=\"@vsxdesign\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"valerio sanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/\"},\"author\":{\"name\":\"valerio sanna\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/person\\\/09283cb51d9fb4611174ef2ae909f14d\"},\"headline\":\"Battere il mercato azionario \u00e8 possibile con i computer?\",\"datePublished\":\"2025-08-07T08:33:15+00:00\",\"dateModified\":\"2025-08-07T08:33:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/\"},\"wordCount\":1077,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1\",\"articleSection\":[\"Investimenti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/\",\"name\":\"Battere il mercato azionario \u00e8 possibile con i computer? - vsx blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1\",\"datePublished\":\"2025-08-07T08:33:15+00:00\",\"dateModified\":\"2025-08-07T08:33:16+00:00\",\"description\":\"Ci aspettiamo molto dall'intelligenza artificiale ma ecco qualcosa che forse non avremo mai: un computer per battere il mercato azionario\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1\",\"width\":1024,\"height\":576,\"caption\":\"computer per battere il mercato azionario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/economia\\\/investimenti\\\/battere-il-mercato-azionario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Battere il mercato azionario \u00e8 possibile con i computer?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\",\"name\":\"vsx blog\",\"description\":\"il mio punto di vista sul web, la tecnologia e l&#039;innovazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\",\"name\":\"VSX design\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/VSX_logo_2017-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/VSX_logo_2017-1.png\",\"width\":346,\"height\":133,\"caption\":\"VSX design\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vsxdesign\\\/\",\"https:\\\/\\\/x.com\\\/vsxdesign\",\"https:\\\/\\\/www.instagram.com\\\/buonumorismo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/valerio-sanna\",\"https:\\\/\\\/www.pinterest.it\\\/vsxblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/person\\\/09283cb51d9fb4611174ef2ae909f14d\",\"name\":\"valerio sanna\",\"description\":\"Vsx Blog : il mio punto di vista sul mondo del web, dell'innovazione e della scienza.\",\"sameAs\":[\"http:\\\/\\\/www.vsxdesign.com\\\/blog\",\"https:\\\/\\\/x.com\\\/vsxdesign\"],\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/author\\\/valerio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Battere il mercato azionario \u00e8 possibile con i computer? - vsx blog","description":"Ci aspettiamo molto dall'intelligenza artificiale ma ecco qualcosa che forse non avremo mai: un computer per battere il mercato azionario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/","og_locale":"it_IT","og_type":"article","og_title":"Battere il mercato azionario \u00e8 possibile con i computer? - vsx blog","og_description":"Ci aspettiamo molto dall'intelligenza artificiale ma ecco qualcosa che forse non avremo mai: un computer per battere il mercato azionario","og_url":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/","og_site_name":"vsx blog","article_publisher":"https:\/\/www.facebook.com\/vsxdesign\/","article_published_time":"2025-08-07T08:33:15+00:00","article_modified_time":"2025-08-07T08:33:16+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg","type":"image\/jpeg"}],"author":"valerio sanna","twitter_card":"summary_large_image","twitter_creator":"@vsxdesign","twitter_site":"@vsxdesign","twitter_misc":{"Scritto da":"valerio sanna","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#article","isPartOf":{"@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/"},"author":{"name":"valerio sanna","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/person\/09283cb51d9fb4611174ef2ae909f14d"},"headline":"Battere il mercato azionario \u00e8 possibile con i computer?","datePublished":"2025-08-07T08:33:15+00:00","dateModified":"2025-08-07T08:33:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/"},"wordCount":1077,"commentCount":0,"publisher":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1","articleSection":["Investimenti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/","url":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/","name":"Battere il mercato azionario \u00e8 possibile con i computer? - vsx blog","isPartOf":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#primaryimage"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1","datePublished":"2025-08-07T08:33:15+00:00","dateModified":"2025-08-07T08:33:16+00:00","description":"Ci aspettiamo molto dall'intelligenza artificiale ma ecco qualcosa che forse non avremo mai: un computer per battere il mercato azionario","breadcrumb":{"@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1","width":1024,"height":576,"caption":"computer per battere il mercato azionario"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vsxdesign.com\/blog\/economia\/investimenti\/battere-il-mercato-azionario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vsxdesign.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Battere il mercato azionario \u00e8 possibile con i computer?"}]},{"@type":"WebSite","@id":"https:\/\/www.vsxdesign.com\/blog\/#website","url":"https:\/\/www.vsxdesign.com\/blog\/","name":"vsx blog","description":"il mio punto di vista sul web, la tecnologia e l&#039;innovazione","publisher":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vsxdesign.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vsxdesign.com\/blog\/#organization","name":"VSX design","url":"https:\/\/www.vsxdesign.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/03\/VSX_logo_2017-1.png","contentUrl":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/03\/VSX_logo_2017-1.png","width":346,"height":133,"caption":"VSX design"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vsxdesign\/","https:\/\/x.com\/vsxdesign","https:\/\/www.instagram.com\/buonumorismo\/","https:\/\/www.linkedin.com\/in\/valerio-sanna","https:\/\/www.pinterest.it\/vsxblog"]},{"@type":"Person","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/person\/09283cb51d9fb4611174ef2ae909f14d","name":"valerio sanna","description":"Vsx Blog : il mio punto di vista sul mondo del web, dell'innovazione e della scienza.","sameAs":["http:\/\/www.vsxdesign.com\/blog","https:\/\/x.com\/vsxdesign"],"url":"https:\/\/www.vsxdesign.com\/blog\/author\/valerio\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/05\/computer-per-battere-il-mercato.jpg?fit=1024%2C576&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/15537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/comments?post=15537"}],"version-history":[{"count":1,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/15537\/revisions"}],"predecessor-version":[{"id":15538,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/15537\/revisions\/15538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/media\/6457"}],"wp:attachment":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/media?parent=15537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/categories?post=15537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/tags?post=15537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}