{"id":15018,"date":"2024-06-24T09:22:19","date_gmt":"2024-06-24T07:22:19","guid":{"rendered":"https:\/\/www.vsxdesign.com\/blog\/?p=15018"},"modified":"2024-06-24T09:22:21","modified_gmt":"2024-06-24T07:22:21","slug":"parole-che-funzionano-sui-social","status":"publish","type":"post","link":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/","title":{"rendered":"Le parole che funzionano sui social: Marketing conversazionale"},"content":{"rendered":"\n<p>Tra gli aggiornamenti del <strong>GDPR<\/strong> e il raggiungimento della copertura globale di Facebook, gli esperti di <a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/video-marketing-per-startup\/\">marketing<\/a> sono allerta.&nbsp;Ora pi\u00f9 che mai, dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l&#8217;attenzione su Facebook, per costruire le nostre strategie intorno ad essi.<\/p>\n\n\n\n<p>Per coloro che sono abituati a pensare in termini di tattiche e trucchi, questa notizia pu\u00f2 essere un sollievo: <strong>relax, amore e umanit\u00e0<\/strong> sono le chiavi! Nel <strong>marketing conversazionale<\/strong> bisogna usare parole che piacciono al tuo pubblico.<\/p>\n\n\n\n<p>In questo articolo esamineremo il potere della conversazione e le parole che il pubblico ama leggere. Imparerai come massimizzare la forza del marketing conversazionale:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>I <a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/social\/intelligenza-artificiale-generativa\/\">social media<\/a> riguardano pi\u00f9 il ritorno sul coinvolgimento (ROC) e meno il ritorno sull&#8217;investimento (ROI).&nbsp;<\/p>\n<\/blockquote>\n\n\n\n<p>Brooke B. Sellas<\/p>\n\n\n\n<p>E, se siamo onesti con noi stessi, concorderemo sul fatto che la chiave per una strategia social di successo \u00e8 sempre stata <a href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/colmare-il-divario-tra-contenuti-sul-sito-web-e-coinvolgimento-nei-social-media\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"l'attenzione per i contenuti (opens in a new tab)\">l&#8217;attenzione per i contenuti<\/a>.&nbsp;Le modifiche dell&#8217;algoritmo di Facebook rafforzano semplicemente la necessit\u00e0 di <a rel=\"noreferrer noopener\" aria-label=\"contenuti di qualit\u00e0 (opens in a new tab)\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/come-ricercare-e-creare-contenuti-sempreverdi\/\" target=\"_blank\">contenuti di qualit\u00e0<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-marketing-conversazionale-l-antidoto-al-declino\">Marketing conversazionale: l&#8217;antidoto al declino<\/h2>\n\n\n\n<p>Ho fatto una ricerca su connessioni di successo, coinvolgimento e strategie sui social media, per preparare un <a rel=\"noreferrer noopener\" aria-label=\"corso di marketing (opens in a new tab)\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/limportanza-del-piano-di-web-marketing\/\" target=\"_blank\">corso di marketing<\/a> che ho svolto.<\/p>\n\n\n\n<p>La mia ricerca si \u00e8 concentrata sulla&nbsp;<a href=\"https:\/\/en.wikipedia.org\/wiki\/Social_penetration_theory\">teoria della penetrazione sociale&nbsp;<\/a>, nota anche come <strong>teoria della cipolla<\/strong>.&nbsp;Fondamentalmente, negli anni &#8217;60, due psicologi hanno affermato che gli esseri umani costruiscono relazioni basate sulle rivelazioni che fanno l&#8217;un l&#8217;altro.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Se voglio conoscerti, divulgher\u00f2 informazioni su di me nel tentativo di farti divulgare informazioni su di te.<\/p>\n<\/blockquote>\n\n\n\n<p>Man mano che gli psicologi approfondivano, si resero conto che non tutte le divulgazioni sono uguali.&nbsp;In realt\u00e0 abbiamo quattro livelli di divulgazione:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>i clich\u00e8<\/strong> (luoghi comuni)<\/li>\n\n\n\n<li><strong>i fatti<\/strong><\/li>\n\n\n\n<li><strong>le opinioni<\/strong><\/li>\n\n\n\n<li><strong>i sentimenti<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Come puoi immaginare, quando conosciamo qualcuno, ci spostiamo da ciascuna delle quattro fasi fino a raggiungere livelli sempre pi\u00f9 profondi di comprensione dell&#8217;altro.<\/p>\n\n\n\n<p>Ovviamente, la maggior parte delle interazioni sui social media si collocano ai livelli uno e due (luoghi comuni e fatti).<\/p>\n\n\n\n<p>La mia ricerca ha esaminato le interazioni dei social media e ha tentato di porre questa domanda:&nbsp;<strong><em>divulgazioni pi\u00f9 profonde, come opinioni e sentimenti, portano a interazioni pi\u00f9 profonde per i social e le loro comunit\u00e0?<\/em><\/strong><\/p>\n\n\n\n<p>La risposta breve?&nbsp;S\u00ec.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-i-luoghi-comuni-stanno-saturando-i-post\"><span class=\"ez-toc-section\" id=\"I_luoghi_comuni_stanno_saturando_i_post\"><\/span>I luoghi comuni stanno saturando i post<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Sono sicuro di non doverti dire che aspetto ha il marketing conversazionale di fascia bassa o clich\u00e9.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per i luoghi comuni, pensa a meme o citazioni sovrapposti a belle immagini<\/li>\n\n\n\n<li>Per la verit\u00e0, guarda quasi tutti i post di blog che vengono condivisi sui social media e otterrai qualcosa del tipo: \u201cI grandi contenuti richiedono molta attenzione.&nbsp;Leggi il nostro post su bla bla bla facendo clic qui sotto &#8230; &#8220;<\/li>\n<\/ul>\n\n\n\n<p>Non sto dicendo che devi buttare il bambino con l&#8217;acqua sporca, ma questo tipo di post riceve clamorosamente un basso coinvolgimento o nessun coinvolgimento sui social.<\/p>\n\n\n\n<p>Il grande aumento dei contenuti sui social media significa che c&#8217;\u00e8 una maggiore competizione basata sulla qualit\u00e0.<\/p>\n\n\n\n<p>La ricerca continua evidenziando il tipo di contenuto che non ha visto un calo delle condivisioni o del coinvolgimento: il contenuto di qualit\u00e0.&nbsp;Il marketing conversazionale, per la sua profondit\u00e0 e le discussioni che avvia, si adatta a questa categoria.<\/p>\n\n\n\n<p>I post di qualit\u00e0 sui social media, spesso usano interazioni pi\u00f9 profonde come opinioni e sentimenti per ottenere un ritorno sulla conversazione.<\/p>\n\n\n\n<p>L&#8217;uso di domande sul tipo di sentimento da generare ti porter\u00e0 lontano.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Qual \u00e8 la tua convinzione quando si tratta di [argomento]?<\/strong><\/li>\n\n\n\n<li><strong>Cosa ne pensi di [argomento]?<\/strong><\/li>\n\n\n\n<li><strong>Come ti fa sentire [il tuo prodotto \/ marchio]?<\/strong><\/li>\n\n\n\n<li><strong>Apprezzi [prodotti o servizi simili ai tuoi]?<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Per essere <strong><a rel=\"noreferrer noopener\" aria-label=\"rilevante sui social media (opens in a new tab)\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/come-usare-linfluencer-marketing-per-promuovere-i-tuoi-contenuti\/\" target=\"_blank\">rilevante sui social media<\/a><\/strong> oggi, dovrai pensare di pi\u00f9 alle conversazioni che stai avendo.<\/p>\n\n\n\n<p>Se condividi solo citazioni e meme di clich\u00e9, il tuo coinvolgimento sar\u00e0 un clich\u00e9.&nbsp;Se presenti solo i fatti, probabilmente riceverai in cambio solo informazioni.<\/p>\n\n\n\n<p>Ma se usi il marketing conversazionale per pubblicizzare opinioni e chiedere sentimenti, potresti benissimo ricevere opinioni, sentimenti e interazioni di livello pi\u00f9 profondo dalle tue comunit\u00e0 online.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-l-amore-e-il-carburante-del-marketing-conversazionale\">L&#8217;amore \u00e8 il carburante del Marketing conversazionale<\/h2>\n\n\n\n<p>Guardando post di qualit\u00e0 sui social media, che attirano alcune di quelle interazioni profonde , ho notato una tendenza forte generata dalla parola AMORE.<\/p>\n\n\n\n<p><strong>Subaru<\/strong> la usa da anni.&nbsp;Dai un&#8217;occhiata al loro recente video di Facebook e al modo in cui usano la parola AMORE. Lo so \u00e8 in inglese ma \u00e8 di facile comprensione.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-facebook wp-block-embed-facebook\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/subaruofamerica\/videos\/10155328702571689\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/div><\/figure>\n\n\n\n<p><strong>DSW<\/strong> \u00e8 un altro grande marchio famoso per aver usato la parola amore nei suoi post pubblicitari e sui social media.&nbsp;Guarda come combinano la parola (o emoji del cuore per la parola) amore e i contenuti (in secondo piano) dei loro dipendenti che danno &#8220;amore&#8221; (a cani e gatti, nientemeno!).<\/p>\n\n\n\n<p>Questo \u00e8&nbsp;<em>un<\/em>&nbsp;post che combina una divulgazione di livello pi\u00f9 profondo, animali, nella stessa Pagina di Facebook con il marchio nelle magliette che i dipendenti indossano. Non male vero?<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-handler-delloggetto-incorporato wp-block-embed-handler-delloggetto-incorporato\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/DSW\/posts\/10156512527914306\" data-width=\"552\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/div><\/figure>\n\n\n\n<p>Se gli esperti di marketing aprissero gli occhi e guardassero davvero, vedrebbero spunti ovunque cercando di attirare pi\u00f9 marketing conversazionale con la pi\u00f9 profonda interazione (sentimenti).<\/p>\n\n\n\n<p>Sembra che abbiamo dimenticato che le comunit\u00e0 nascono e prosperano attorno alla comunicazione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-parole-che-funzionano\"><span class=\"ez-toc-section\" id=\"Parole_che_funzionano\"><\/span>Parole che funzionano<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Oltre all&#8217;amore, in che modo puoi usare i social per creare interazioni?<\/p>\n\n\n\n<p>Le parole che di solito funzionano con il marketing conversazionale sono cose come:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Appassionato (&#8220;se sei appassionato di [argomento] come noi, dillo ai tuoi amici!)<\/strong><\/li>\n\n\n\n<li><strong>Accetto (sei d&#8217;accordo &#8230;?)<\/strong><\/li>\n\n\n\n<li><strong>Pensa (dicci cosa ne pensi &#8230;)<\/strong><\/li>\n\n\n\n<li><strong>Senti (raccontaci come ti senti &#8230;)<\/strong><\/li>\n\n\n\n<li><strong>Supporto (mostra il tuo supporto entro &#8230;)<\/strong><\/li>\n\n\n\n<li><strong>Storia (qual \u00e8 la tua storia con [prodotto \/ servizio])<\/strong><\/li>\n\n\n\n<li><strong>Migliora (come possiamo migliorare [argomento]?)<\/strong><\/li>\n\n\n\n<li><strong>Ascolta (vogliamo SENTIRE DA TE!)<\/strong><\/li>\n\n\n\n<li><strong>TU (e molto meno io, io e noi)<\/strong><\/li>\n<\/ul>\n\n\n\n<p>E, secondo un recente rapporto di Sprout Social, il 66% dei consumatori afferma che \u00e8 importante che i marchi prendano posizione pubblica su questioni sociali e politiche.&nbsp;E pi\u00f9 della met\u00e0 (58%) \u00e8 aperta a questo evento sui social media.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/buzzsumo.com\/wp-content\/resize\/uploads\/2018\/07\/Brands-Get-Real-Chart-Sprout-Social-.jpg__w780\" alt=\"Le principali reazioni emotive del consumatore nei confronti di marchi che utilizzano i social media per prendere posizione sulle questioni sociali e politiche - credit sproutsocial\" class=\"wp-image-10506\"\/><figcaption class=\"wp-element-caption\">Le principali reazioni emotive del consumatore nei confronti di marchi che utilizzano i social media per prendere posizione sulle questioni sociali e politiche &#8211; credit sproutsocial<\/figcaption><\/figure>\n<\/div>\n\n\n<p>In altre parole, le persone vogliono &#8220;vedere&#8221; l&#8217;umano dall&#8217;altra parte del loro schermo.&nbsp;Vogliono connettersi con un&#8217;altra persona, non con un logo o una mission aziendale.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Vinceranno le aziende pi\u00f9 umane.<\/p>\n<\/blockquote>\n\n\n\n<p> Mark Schaefer <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-abbiamo-dimenticato-di-essere-umani\"><span class=\"ez-toc-section\" id=\"Abbiamo_dimenticato_di_essere_umani\"><\/span>Abbiamo dimenticato di essere umani?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Infine, mi chiedo se noi esperti di marketing abbiamo dimenticato di essere umani.&nbsp;Sembra un po&#8217; folle che i professionisti del marketing debbano dire agli altri professionisti di agire come un essere umano.<\/p>\n\n\n\n<p>Ci siamo persi cos\u00ec tanto nella tana del bianconiglio degli algoritmi? Clickbait e trucchi di sistema ci hanno fatto scordare che il nostro obiettivo principale \u00e8 connetterci con altri esseri umani?<\/p>\n\n\n\n<p>Possiamo essere fantasiosi e chiamarlo &#8220;marketing conversazionale&#8221; o &#8220;social media marketing&#8221;, ma alla fine della giornata \u00e8 solo una persona in contatto con un&#8217;altra. Teniamolo a mente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra gli aggiornamenti del GDPR e il raggiungimento della copertura globale di Facebook, gli esperti di marketing sono allerta.&nbsp;Ora pi\u00f9 che mai, dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l&#8217;attenzione su Facebook, per costruire le nostre strategie intorno ad essi. Per coloro che sono abituati a pensare in&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[65],"tags":[94],"class_list":["post-15018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-web-marketing-e-seo","tag-marketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le parole che funzionano sui social: Marketing conversazionale - vsx blog<\/title>\n<meta name=\"description\" content=\"Dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l&#039;attenzione degli utenti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le parole che funzionano sui social: Marketing conversazionale - vsx blog\" \/>\n<meta property=\"og:description\" content=\"Dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l&#039;attenzione degli utenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/\" \/>\n<meta property=\"og:site_name\" content=\"vsx blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vsxdesign\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T07:22:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T07:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"valerio sanna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vsxdesign\" \/>\n<meta name=\"twitter:site\" content=\"@vsxdesign\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"valerio sanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/\"},\"author\":{\"name\":\"valerio sanna\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/person\\\/09283cb51d9fb4611174ef2ae909f14d\"},\"headline\":\"Le parole che funzionano sui social: Marketing conversazionale\",\"datePublished\":\"2024-06-24T07:22:19+00:00\",\"dateModified\":\"2024-06-24T07:22:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/\"},\"wordCount\":1144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1\",\"keywords\":[\"marketing\"],\"articleSection\":[\"WebMarketing e Seo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/\",\"name\":\"Le parole che funzionano sui social: Marketing conversazionale - vsx blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1\",\"datePublished\":\"2024-06-24T07:22:19+00:00\",\"dateModified\":\"2024-06-24T07:22:21+00:00\",\"description\":\"Dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l'attenzione degli utenti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1\",\"width\":1024,\"height\":603,\"caption\":\"Parole che funzionano sui social\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/internet\\\/web-marketing-e-seo\\\/parole-che-funzionano-sui-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le parole che funzionano sui social: Marketing conversazionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\",\"name\":\"vsx blog\",\"description\":\"il mio punto di vista sul web, la tecnologia e l&#039;innovazione\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#organization\",\"name\":\"VSX design\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/VSX_logo_2017-1.png\",\"contentUrl\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/VSX_logo_2017-1.png\",\"width\":346,\"height\":133,\"caption\":\"VSX design\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vsxdesign\\\/\",\"https:\\\/\\\/x.com\\\/vsxdesign\",\"https:\\\/\\\/www.instagram.com\\\/buonumorismo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/valerio-sanna\",\"https:\\\/\\\/www.pinterest.it\\\/vsxblog\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/#\\\/schema\\\/person\\\/09283cb51d9fb4611174ef2ae909f14d\",\"name\":\"valerio sanna\",\"description\":\"Vsx Blog : il mio punto di vista sul mondo del web, dell'innovazione e della scienza.\",\"sameAs\":[\"http:\\\/\\\/www.vsxdesign.com\\\/blog\",\"https:\\\/\\\/x.com\\\/vsxdesign\"],\"url\":\"https:\\\/\\\/www.vsxdesign.com\\\/blog\\\/author\\\/valerio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le parole che funzionano sui social: Marketing conversazionale - vsx blog","description":"Dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l'attenzione degli utenti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/","og_locale":"it_IT","og_type":"article","og_title":"Le parole che funzionano sui social: Marketing conversazionale - vsx blog","og_description":"Dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l'attenzione degli utenti","og_url":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/","og_site_name":"vsx blog","article_publisher":"https:\/\/www.facebook.com\/vsxdesign\/","article_published_time":"2024-06-24T07:22:19+00:00","article_modified_time":"2024-06-24T07:22:21+00:00","og_image":[{"width":1024,"height":603,"url":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg","type":"image\/jpeg"}],"author":"valerio sanna","twitter_card":"summary_large_image","twitter_creator":"@vsxdesign","twitter_site":"@vsxdesign","twitter_misc":{"Scritto da":"valerio sanna","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#article","isPartOf":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/"},"author":{"name":"valerio sanna","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/person\/09283cb51d9fb4611174ef2ae909f14d"},"headline":"Le parole che funzionano sui social: Marketing conversazionale","datePublished":"2024-06-24T07:22:19+00:00","dateModified":"2024-06-24T07:22:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/"},"wordCount":1144,"commentCount":0,"publisher":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1","keywords":["marketing"],"articleSection":["WebMarketing e Seo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/","url":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/","name":"Le parole che funzionano sui social: Marketing conversazionale - vsx blog","isPartOf":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#primaryimage"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1","datePublished":"2024-06-24T07:22:19+00:00","dateModified":"2024-06-24T07:22:21+00:00","description":"Dobbiamo sapere quali sono le parole che funzionano sui social e quali post attirano l'attenzione degli utenti","breadcrumb":{"@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#primaryimage","url":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1","width":1024,"height":603,"caption":"Parole che funzionano sui social"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vsxdesign.com\/blog\/internet\/web-marketing-e-seo\/parole-che-funzionano-sui-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vsxdesign.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le parole che funzionano sui social: Marketing conversazionale"}]},{"@type":"WebSite","@id":"https:\/\/www.vsxdesign.com\/blog\/#website","url":"https:\/\/www.vsxdesign.com\/blog\/","name":"vsx blog","description":"il mio punto di vista sul web, la tecnologia e l&#039;innovazione","publisher":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vsxdesign.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.vsxdesign.com\/blog\/#organization","name":"VSX design","url":"https:\/\/www.vsxdesign.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/03\/VSX_logo_2017-1.png","contentUrl":"https:\/\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/03\/VSX_logo_2017-1.png","width":346,"height":133,"caption":"VSX design"},"image":{"@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vsxdesign\/","https:\/\/x.com\/vsxdesign","https:\/\/www.instagram.com\/buonumorismo\/","https:\/\/www.linkedin.com\/in\/valerio-sanna","https:\/\/www.pinterest.it\/vsxblog"]},{"@type":"Person","@id":"https:\/\/www.vsxdesign.com\/blog\/#\/schema\/person\/09283cb51d9fb4611174ef2ae909f14d","name":"valerio sanna","description":"Vsx Blog : il mio punto di vista sul mondo del web, dell'innovazione e della scienza.","sameAs":["http:\/\/www.vsxdesign.com\/blog","https:\/\/x.com\/vsxdesign"],"url":"https:\/\/www.vsxdesign.com\/blog\/author\/valerio\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.vsxdesign.com\/blog\/wp-content\/uploads\/2019\/11\/parole-che-funzionano-sui-social.jpg?fit=1024%2C603&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/15018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/comments?post=15018"}],"version-history":[{"count":1,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/15018\/revisions"}],"predecessor-version":[{"id":15019,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/posts\/15018\/revisions\/15019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/media\/9342"}],"wp:attachment":[{"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/media?parent=15018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/categories?post=15018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vsxdesign.com\/blog\/wp-json\/wp\/v2\/tags?post=15018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}